{"id":19462,"date":"2024-04-02T09:18:57","date_gmt":"2024-04-02T07:18:57","guid":{"rendered":"https:\/\/addwill.eu\/?p=19462"},"modified":"2024-04-02T09:18:57","modified_gmt":"2024-04-02T07:18:57","slug":"quasi-el-60-de-les-pimes-incompleixen-la-regulacio-laboral","status":"publish","type":"post","link":"https:\/\/addwill.eu\/ca\/quasi-el-60-de-les-pimes-incompleixen-la-regulacio-laboral\/","title":{"rendered":"Quasi el 60% de les pimes incompleixen la regulaci\u00f3 laboral"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Al voltant del 60% de les petites i mitjanes empreses (pimes) es troben en situaci\u00f3 d\u2019incompliment respecte a alguna de les regulacions laborals vigents. Segons un informe recent de Thomson Reuters, es destaca que la principal prioritat estrat\u00e8gica per al 61% dels equips de compliment laboral d&#8217;aquestes empreses rau a mantenir-se actualitzats respecte als canvis normatius en aquest \u00e0mbit.<\/p>\n<p style=\"text-align: justify;\">La naturalesa de les obligacions de compliment laboral imposa una c\u00e0rrega significativa sobre les pimes, que sovint es veuen limitades per restriccions financeres i de personal. Aix\u00f2 es tradueix en dificultats per implementar un sistema de gesti\u00f3 integral, contractar personal dedicat al compliment a temps complet o accedir a tecnologies que facilitin i agilitzin els processos relacionats amb el compliment normatiu.<\/p>\n<p style=\"text-align: justify;\">Entre les <strong>obligacions laborals<\/strong> que han de complir es troben:<\/p>\n<ul>\n<li>La implementaci\u00f3 d&#8217;un Pla d&#8217;Igualtat per fomentar l&#8217;equitat de g\u00e8nere.<\/li>\n<li>La garantia de la Prevenci\u00f3 de Riscos Laborals per assegurar la seguretat en el treball.<\/li>\n<li>L&#8217;adopci\u00f3 d&#8217;un Protocol d&#8217;Assetjament per abordar casos de discriminaci\u00f3 sexual o de g\u00e8nere.<\/li>\n<li>El compliment de les normatives de Protecci\u00f3 de Dades per salvaguardar la privadesa de la informaci\u00f3.<\/li>\n<li>La reserva d&#8217;un percentatge de la plantilla per a persones amb discapacitat d&#8217;acord amb la normativa LISMI.<\/li>\n<li>Garantir la desconnexi\u00f3 digital dels treballadors fora de l&#8217;horari laboral.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L\u2019<strong>incompliment d&#8217;aquestes obligacions<\/strong> pot resultar en sancions severes, com multes i accions legals, que podrien amena\u00e7ar la continu\u00eftat operativa de l&#8217;empresa.<\/p>\n<p style=\"text-align: justify;\">En resum, \u00e9s fonamental que les pimes compleixin amb les seves obligacions laborals per evitar sancions i garantir el benestar dels empleats i la continu\u00eftat de l&#8217;empresa.<\/p>\n<p style=\"text-align: justify;\">Us convidem a visitar la nostra publicaci\u00f3 pr\u00e8via &#8220;<a href=\"https:\/\/addwill.eu\/ca\/recordatori-important-obligacions-laborals-clau-per-a-totes-les-empreses\/\"><em><strong>Recordatori important: Obligacions laborals clau per a totes les empreses<\/strong><\/em><\/a>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Si necessiteu m\u00e9s informaci\u00f3 o assessorament, no dubteu a contactar amb els experts del nostre departament jur\u00eddic laboral. Des d\u2019<strong>addwill<\/strong>, podem ajudar-vos a complir amb totes aquestes obligacions laborals i garantir el benestar de la vostra empresa i els vostres empleats.<\/p>\n<p style=\"text-align: justify;\">Podeu contactar amb nosaltres via telef\u00f2nica al 93 487 52 00, per correu electr\u00f2nic a comunicacio@addwill.eu, o enviar la vostra consulta fent <a href=\"https:\/\/addwill.eu\/ca\/contactar\/\"><em>clic aqu\u00ed<\/em><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Al voltant del 60% de les petites i mitjanes empreses (pimes) es troben en situaci\u00f3 d\u2019incompliment respecte a alguna de les regulacions laborals  [&#8230;]<\/p>\n","protected":false},"author":12,"featured_media":19458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1002],"tags":[],"class_list":["post-19462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laboral-ca"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/posts\/19462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/comments?post=19462"}],"version-history":[{"count":3,"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/posts\/19462\/revisions"}],"predecessor-version":[{"id":19469,"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/posts\/19462\/revisions\/19469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/media\/19458"}],"wp:attachment":[{"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/media?parent=19462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/categories?post=19462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/addwill.eu\/ca\/wp-json\/wp\/v2\/tags?post=19462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}